{"id":1428,"date":"2025-10-22T16:13:25","date_gmt":"2025-10-22T21:13:25","guid":{"rendered":"https:\/\/mercator.pe\/?page_id=1428"},"modified":"2026-01-29T15:59:12","modified_gmt":"2026-01-29T20:59:12","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/mail.mercator.com.pe\/en\/terminos-y-condiciones\/","title":{"rendered":"Terms and conditions"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1428\" class=\"elementor elementor-1428\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ae2fe4 grupo--compacto e-flex e-con-boxed e-con e-parent\" data-id=\"0ae2fe4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d21a43e elementor-widget elementor-widget-heading\" data-id=\"d21a43e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Terms and conditions<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1638b2fc grupo e-flex e-con-boxed e-con e-parent\" data-id=\"1638b2fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67e8cf18 elementor-widget elementor-widget-text-editor\" data-id=\"67e8cf18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\n<p class=\"wp-block-paragraph\">Thank you for visiting this web site. Please read carefully the\u00a0<strong>TERMS AND CONDITIONS OF USE<\/strong>\u00a0contained in this document and any use of this web site constitutes your acceptance and\/or expressed to the same. In other words, every time you use this web site you are agreeing to all the Terms and Conditions set forth herein.<\/p>\n<h2>1.- GENERAL TERMS AND CONDITIONS AND THE ACCEPTANCE OF THE USER<\/h2>\n<p>This website (hereinafter the \u201cWebsite\u201d) is owned by\u00a0<strong>MERCATOR PER\u00da S.A.C.<\/strong>\u00a0(en adelante \u201cMERCATOR\u201d). El acceso a este Sitio es gratuito y solo est\u00e1 condicionado a la aceptaci\u00f3n y cumplimiento de estos T\u00e9rminos y Condiciones de Uso y nuestra Pol\u00edtica de Privacidad. El ingreso a, o registro en, este Sitio otorga a la persona el car\u00e1cter de usuario del Sitio (en adelante \u201cUsuario\u201d), e implica una aceptaci\u00f3n total e incondicional a las cl\u00e1usulas, condiciones, advertencias y t\u00e9rminos de uso que a continuaci\u00f3n se indican, as\u00ed como de aquellas condiciones previstas y contempladas en nuestra Pol\u00edtica de Privacidad, la cual recoge las exigencia contempladas en la Ley de Protecci\u00f3n de Datos Personales (Ley 29733) y su Reglamento (D.S.003-2013-JUS). MERCATOR se reserva el derecho de modificar y actualizar unilateralmente estos T\u00e9rminos y Condiciones de Uso. Estas modificaciones y actualizaciones ser\u00e1n publicadas en este Sitio. Los T\u00e9rminos y Condiciones que rigen son los \u00faltimos publicados en el Sitio, por lo que el Usuario tiene la responsabilidad de estar al tanto de estas modificaciones y actualizaciones.<\/p>\n<p>This acceptance will be deemed granted from the moment that the User is using and\/or registering on the Site. If the User does not agree with these Terms and Conditions of Use you should refrain from entering, using and\/or registering on this Site. Therefore, prior to the entry, use of and\/or registration of the Site, the User must read carefully the Terms and Conditions of Use and our Privacy Policy applicable to the Site. The lack of knowledge of the User of these Terms and Conditions of Use shall not involve the application of the provisions and clauses contained in the same.<\/p>\n<p>Por regla general, este Sitio es solamente de car\u00e1cter informativo y relacional, y tiene por objeto dar informaci\u00f3n a los Usuarios sobre MERCATOR, sus productos, servicios, promociones y otra informaci\u00f3n que MERCATOR pueda considerar \u00fatil para los Usuarios. En este sentido, la informaci\u00f3n proporcionada por MERCATOR a trav\u00e9s de este no constituye una oferta en t\u00e9rminos legales y la sola visita al Sitio por parte del Usuario no constituye aceptaci\u00f3n en t\u00e9rminos legales, y por lo tanto no impone al Usuario obligaci\u00f3n alguna. En consecuencia, las relaciones contractuales que deriven de la informaci\u00f3n que recibe el Usuario a trav\u00e9s de este Sitio requerir\u00e1n de su confirmaci\u00f3n por escrito por parte de MERCATOR. Excepcionalmente, cuando este Sitio ofrezca a sus Usuarios la celebraci\u00f3n de contratos a trav\u00e9s de medio electr\u00f3nicos, \u00e9stos se regir\u00e1n por las normas de la Rep\u00fablica del Per\u00fa.<\/p>\n<h2>2.- DEFINITION AND INSTRUMENTALIZACION OF THE SITE<\/h2>\n<p>Este Sitio ha sido creado por MERCATOR con el fin de crear una comunidad participativa alrededor de contenidos y beneficios, que permitan un di\u00e1logo constante y retroactivo entre sus integrantes y MERCATOR.<\/p>\n<p>As\u00ed, seg\u00fan lo se\u00f1alado en el p\u00e1rrafo anterior, los Usuarios del Sitio se obligan a respetar los T\u00e9rminos y Condiciones de Uso del mismo y se comprometen a que las publicaciones de contenidos, datos, informaciones u opiniones que hagan en el Sitio se basen en el respeto mutuo, el orden p\u00fablico y las buenas costumbres, de manera que no causen da\u00f1o a MERCATOR ni a otros Usuarios, y que no obstaculicen la buena convivencia entre \u00e9stos. Por ello los contenidos entregados por los Usuarios deben ser objetivos y veraces, dejando de lado cualquier propuesta o menci\u00f3n a temas que pudiesen instar al odio, confusi\u00f3n, divisi\u00f3n de sus miembros y\/o cualquier situaci\u00f3n negativa para la comunidad.<\/p>\n<h2>3.- MODIFICATION OF THE INFORMATION<\/h2>\n<p>MERCATOR se reserva la facultad y el derecho de actualizar, modificar o eliminar, en parte o en todo, y sin expresi\u00f3n de causa, cualquier contenido o informaci\u00f3n publicada en este Sitio seg\u00fan lo estime conveniente, pudiendo hacer uso de tal facultad en cualquier momento y sin previo aviso. Este derecho abarca los contenidos referidos a disponibilidad o stock de productos o servicios, especificaciones, precio, o en cuanto a la configuraci\u00f3n y funcionalidades del Sitio o de la informaci\u00f3n de actividades promocionales.<\/p>\n<h2>4.- SITE CONTENT<\/h2>\n<p>Los productos y servicios, las funcionalidades y las promociones que MERCATOR describe en este Sitio est\u00e1n ofrecidos \u00fanicamente para el territorio nacional de la Rep\u00fablica de Per\u00fa.<\/p>\n<h2>5.- NAVIGATION, ACCESS AND SECURITY<\/h2>\n<p>El acceso y navegaci\u00f3n en este Sitio supone aceptar y conocer las advertencias legales, condiciones y t\u00e9rminos de uso contenidas en el mismo. MERCATOR realiza los m\u00e1ximos esfuerzos para que el acceso y la navegaci\u00f3n en este Sitio se realicen en las mejores condiciones, evitando perjuicios de cualquier tipo que pudiesen ocasionarse durante los mismos.<\/p>\n<p>MERCATOR no se responsabiliza ni garantiza que el acceso a este Sitio sea ininterrumpido o que est\u00e9 libre de error, ni por las fallas en rendimiento, omisiones, interrupciones de servicio, defectos, demoras en la transmisi\u00f3n o fallas en las l\u00edneas de conexi\u00f3n. Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio, est\u00e9 libre de error o no cause da\u00f1os.<\/p>\n<p>MERCATOR hace todos los esfuerzos a su alcance para que este Sitio no contenga ning\u00fan virus inform\u00e1tico que pueda causar da\u00f1os a los Usuarios. A pesar de estos esfuerzos, MERCATOR declara que es imposible garantizar en todo momento que este Sitio est\u00e9 libre de virus inform\u00e1ticos, y por lo tanto, en ning\u00fan caso MERCATOR ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso y el uso de este Sitio, incluy\u00e9ndose pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus. MERCATOR no se hace responsable de los da\u00f1os que pudiesen ocasionarse a los Usuarios por un uso inadecuado de este Sitio.<\/p>\n<h2>6.- OBLIGATIONS OF THE USER<\/h2>\n<p>Without prejudice to the above, the User is obliged to:<\/p>\n<p>6.1. Use diligently the User name and passwords are personal assigned to the User, in your case.<\/p>\n<p>6.2. Seguir las instrucciones impartidas por MERCATOR sobre el uso del Sitio.<\/p>\n<p>6.3. Usar el Sitio, sus Servicios y Materiales en forma correcta, l\u00edcita y s\u00f3lo para fines de informaci\u00f3n personal, no pudiendo hacer uso del mismo para fines comerciales o que puedan da\u00f1ar en cualquier forma a MERCATOR.<\/p>\n<p>6.4. Use the Materials in the forms permitted by the law, refraining to give them a use that is contrary to morals, good customs or public order.<\/p>\n<h2>7.- THE RESPONSIBILITY OF THE USER<\/h2>\n<p>The User agrees that the use of this Site and the Materials and Services included therein, are free and voluntary, and that such use and its consequences are of sole responsibility of the User.<\/p>\n<p>El Usuario responder\u00e1 de los da\u00f1os y perjuicios de todo tipo, directos o indirectos, que MERCATOR, otros Usuarios o terceros puedan sufrir como consecuencia de la infracci\u00f3n, por parte del Usuario, de cualquiera de los t\u00e9rminos a que \u00e9ste se obliga mediante los presentes T\u00e9rminos y Condiciones de Uso, o de la infracci\u00f3n a las normas vigentes aplicables.<\/p>\n<p>Sin perjuicio de lo anterior, si como consecuencia de un incumplimiento del Usuario de estos T\u00e9rminos y Condiciones de Uso, MERCATOR fuere obligada a pagar multas, indemnizaciones u otro tipo de compensaciones, que resulten de la aplicaci\u00f3n de una medida administrativa o de una resoluci\u00f3n judicial, el Usuario deber\u00e1 reembolsar a MERCATOR la totalidad de los montos pagados por tal motivo, incluyendo honorarios de asesores externos.<\/p>\n<h2>8.- EXCLUSION OF WARRANTIES<\/h2>\n<p>MERCATOR ha realizado de buena fe este Sitio para ofrecer a sus usuarios y p\u00fablico en general Servicios de calidad, confiables y seguros.<\/p>\n<p>El Usuario reconoce y acepta que, por su naturaleza, la prestaci\u00f3n de servicio de este Sitio, sus Servicios y Materiales, conlleva riesgos, contingencias o eventualidades de imposible o dif\u00edcil detecci\u00f3n y control por parte de MERCATOR, y que eventualmente pueden causar perjuicios al Usuario.<\/p>\n<p>Consequently, the User accepts the provision of the service of this Site, Services and Materials, in the condition in which it was effectively delivered and assumes personally the consequences of their decision to make use of the same.<\/p>\n<p>MERCATOR no garantiza en caso alguno:<\/p>\n<ol>\n<li>The accuracy or truthfulness of any of the information contained on the Website, the Services or the Materials.<\/li>\n<li>The availability, continuity, accessibility, performance, operation or quality of the Site, the Services or the Materials.<\/li>\n<li>The legality, reliability, quality, usefulness or veracity of the information, absence of viruses or other harmful elements of the Services or the Site Materials.<\/li>\n<li>The accuracy or validity or authenticity of the information of the personal data provided by Users.<\/li>\n<li>Compliance, on the part of the Users, of the law, the Terms and Conditions of Use, morals, good customs or public order, in the access or use of the Site, Services, and Materials.<\/li>\n<\/ol>\n<h2>9.- RESPONSABILIDAD DE MERCATOR<\/h2>\n<p>MERCATOR no se hace responsable por los da\u00f1os o perjuicios, de cualquier naturaleza que estos sean, directos o indirectos, que se produzcan como consecuencia de o con ocasi\u00f3n o en relaci\u00f3n con el uso que el Usuario haga del Sitio, los Servicios o los Materiales.<\/p>\n<p>The information, suggestions or tips that appear on the Site are intended to be a general guide for information purposes, and help, and in no case replaces the professional advice in matters of personal, medical, legal, tax, accounting, financial or of any other kind. The User should consult an appropriate professional for specific information according to your personal situation.<\/p>\n<p>Asimismo, los enlaces y v\u00ednculos no implican responsabilidad alguna para la Empresa ni aprobaci\u00f3n por parte de \u00e9sta respecto de la informaci\u00f3n contenida en los mismos; los enlaces e hiper conexiones con otros medios de Internet son a su propio riesgo; MERCATOR no investiga, no verifica, no controla ni respalda el contenido, exactitud, legalidad y opiniones expresadas en otras conexiones suministradas por estos medios.<\/p>\n<p>MERCATOR garantiza la confidencialidad de la informaci\u00f3n personal del Usuario, la cual s\u00f3lo ser\u00e1 usada para los efectos propios de sus promociones.<\/p>\n<h2>10.- DERECHOS DE PROPIEDAD INTELECTUAL E INDUSTRIAL DE PROPIEDAD DE MERCATOR<\/h2>\n<p>La totalidad de la informaci\u00f3n que contiene este Sitio, ser\u00e1 considerada para todos los efectos legales de propiedad de MERCATOR PER\u00da S.A.C., pudiendo utilizar con cualquier fin toda idea, concepto, conocimiento o t\u00e9cnica incluidas en la informaci\u00f3n que proporcione un visitante a trav\u00e9s de este Sitio.<\/p>\n<p>MERCATOR no estar\u00e1 sujeto a obligaci\u00f3n alguna en cuanto a la confidencialidad de la informaci\u00f3n presentada, salvo acuerdo en contrario entre la empresa y sus clientes, proveedores y asociados, y las exigencias legales que rigen actualmente al respecto y las que se incorporen en el futuro.<\/p>\n<p>Los derechos de propiedad intelectual de estas p\u00e1ginas, de las pantallas que muestran estas p\u00e1ginas, de la informaci\u00f3n y material que aparecen en las mismas y de su disposici\u00f3n, pertenecen a MERCATOR, salvo lo indicado en el punto 11 siguiente.<\/p>\n<p>Este Sitio y los contenidos que alberga se encuentran protegidos por las leyes de Propiedad Industrial e Intelectual, y por los tratados internacionales suscritos y ratificados por la Rep\u00fablica del Per\u00fa. Estos contenidos no podr\u00e1n ser objeto de explotaci\u00f3n, reproducci\u00f3n, distribuci\u00f3n, modificaci\u00f3n, comunicaci\u00f3n p\u00fablica, cesi\u00f3n o transformaci\u00f3n, ni de ning\u00fan otro acto jur\u00eddico por parte de un tercero no autorizado expresamente y por escrito por MERCATOR. El acceso a este Sitio no otorga a los usuarios derecho, ni titularidad alguna sobre los derechos de propiedad intelectual de los contenidos que alberga este Sitio.<\/p>\n<p>The contents of this Site can be downloaded to the terminal of the user), provided that it is for their private use immediately and without any commercial purpose. Therefore the User will not be able to exploit, reproduce, distribute, modify, publicly display, transfer, transform, or use the content of this Site for public or commercial purposes.<\/p>\n<p>MERCATOR no transfiere a los Usuarios la propiedad de su software. El Usuario es el propietario del soporte en el cual es software es grabado. MERCATOR retiene todos los derechos de propiedad industrial e intelectual incluyendo el software. Si el Usuario transfiere software de este Sitio a su terminal, no podr\u00e1 diseccionarlo para su estudio, o descompilarlo, traducir la versi\u00f3n del c\u00f3digo objeto original o su lenguaje a otro c\u00f3digo o lenguaje.<\/p>\n<p>Todas las marcas, logotipos, dise\u00f1os, frases de propaganda, y en general todos los signos distintivos mostrados en este Sitio son propiedad de MERCATOR o de terceros o empresas ligadas que han autorizado el uso de los mismos a MERCATOR. Se proh\u00edbe a los Usuarios y a terceros usar estos signos distintivos, descargarlos permanentemente, copiarlos o distribuirlos por cualquier medio sin el permiso escrito de MERCATOR o de la tercera empresa titular de los derechos.<\/p>\n<h2>11.- CONTRIBUTIONS OF THIRD PARTIES<\/h2>\n<p>La legitimidad de los derechos de propiedad intelectual o industrial correspondientes a los contenidos aportados por Usuarios o por terceros es de la exclusiva responsabilidad de los mismos. A los efectos de preservar los posibles derechos de propiedad intelectual, en el caso de que cualquier Usuario o un tercero considere que se ha producido una violaci\u00f3n de sus leg\u00edtimos derechos por la introducci\u00f3n de un determinado contenido en el Sitio, deber\u00e1 notificar dicha circunstancia, por escrito, a MERCATOR PER\u00da S.A.C.<\/p>\n<p>Sin perjuicio de lo anterior, al momento de acceder o registrarse en el Sitio, y por lo tanto aceptar los T\u00e9rminos y Condiciones de Uso se\u00f1aladas en este texto, el Usuario se compromete a hacer un uso adecuado de los Materiales y Servicios que son ofrecidos a trav\u00e9s del Sitio, y a no emplearlos para (a) incurrir en actividades il\u00edcitas, ilegales o contrarias a la buena fe y al orden p\u00fablico; ni (b) difundir contenidos o propaganda de car\u00e1cter racista, xen\u00f3fobo, pornogr\u00e1fico, de apolog\u00eda del terrorismo o atentatorio contra los derechos humanos; ni (c) provocar da\u00f1os en los sistemas f\u00edsicos y l\u00f3gicos de MERCATOR o sus empresas asociadas, de sus proveedores o de terceras personas, introducir o difundir en la red virus inform\u00e1ticos o cualesquiera otros sistemas f\u00edsicos o l\u00f3gicos que sean susceptibles de provocar los da\u00f1os anteriormente mencionados; ni (d) difundir contenidos que atenten contra la imagen y reputaci\u00f3n de MERCATOR o de terceros.<\/p>\n<p>El Usuario declara y garantiza a MERCATOR que posee todos los derechos de Propiedad Intelectual sobre los mensajes y contenidos que introduzca en el Sitio.<\/p>\n<h2>12.- TRANSFER OF RIGHTS<\/h2>\n<p>Con el mero env\u00edo de un trabajo, colaboraci\u00f3n, receta, imagen, comentario, entre otros, el Usuario faculta a MERCATOR, adem\u00e1s de a incluirlo en el Sitio, para, por s\u00ed misma o mediante su cesi\u00f3n a terceros, proceder a su reproducci\u00f3n, distribuci\u00f3n y comunicaci\u00f3n p\u00fablica, en versi\u00f3n completa, condensada, adaptada o abreviada, gratuita u onerosamente, en todo el mundo, en todos los idiomas, en otros productos que realice, y para todo tipo de usos. Los derechos cedidos podr\u00e1n ser ejercitados en formato impreso, en cualesquiera modalidades de edici\u00f3n, en soporte electr\u00f3nico (\u00f3ptico, magn\u00e9tico, magn\u00e9tico-\u00f3ptico o digital) u otros soportes tecnol\u00f3gicamente adaptables al formato solicitado por este Sitio.<\/p>\n<p>La inclusi\u00f3n en el Sitio de elementos proporcionados por los Usuarios no implica respaldo, patrocinio o recomendaci\u00f3n alguna de MERCATOR sobre los mismos, por lo que MERCATOR no ser\u00e1 responsable en absoluto respecto de su contenido y licitud.<\/p>\n<p>MERCATOR tendr\u00e1 plena libertad de decisi\u00f3n sobre si las colaboraciones y mensajes enviados son finalmente publicadas en el Sitio o no, quedando facultada para retirarlos cuando estime oportuno, pudiendo publicar los contenidos suministrados por el Usuario de forma parcial, resumida o abreviada, sin ulterior responsabilidad.<\/p>\n<h2>13.- AUTHORIZATION AND USE OF PERSONAL DATA<\/h2>\n<p>La Ley peruana de Protecci\u00f3n de Datos Personales establece que para efectuar el tratamiento de los datos de una persona es necesario su consentimiento previo, informado, expreso e inequ\u00edvoco, y adem\u00e1s por escrito, en caso de datos sensibles. Por tal motivo, en el presente entorno digital, se considerar\u00e1 expresa su manifestaci\u00f3n cuando al pregunt\u00e1rsele su aceptaci\u00f3n por el presente documento, usted disponga de manera positiva en \u201chacer clic\u201d, \u201ccliquear\u201d o \u201cpinchar\u201d, \u201cdar un toque\u201d, \u201ctouch\u201d o \u201cpad\u201d u otros similares . MERCATOR entender\u00e1 que usted ha entregado su consentimiento escrito para el tratamiento de sus datos personales.<\/p>\n<p>MERCATOR considera importante que usted tenga conocimiento de lo siguiente:<\/p>\n<p><strong>\u00bfQu\u00e9 informaci\u00f3n personal recolecta MERCATOR a trav\u00e9s de estos sitios web y c\u00f3mo la recolecta?<\/strong><\/p>\n<p>Only collect the personal information YOU want to provide to or that is necessary to give (or improve) our service to you. We collect personal information directly such as full names, type and number of identity document, company name, number of RUC, address, email address, contact telephone number; as indirect information as \"cookies\" (information on user preferences when you visit a web page), connections and information systems, all of it in strict compliance with Law No. 29733, Law on the Protection of Personal Data and the D. S. 003-2013-JUS, Regulation.<\/p>\n<p>Usted puede confiar que MERCATOR toma todas las precauciones necesarias para mantener su informaci\u00f3n personal que nos ha sido enviada, de manera privada y segura.<\/p>\n<p><strong>\u00bfC\u00f3mo puede MERCATOR mantener su informaci\u00f3n personal segura?<\/strong><\/p>\n<p>MERCATOR toma todas las medidas de precauci\u00f3n necesarias para mantener su informaci\u00f3n personal privada, confidencial y segura. Solo personal autorizado MERCATOR, del Grupo Transmeridian, personal de compa\u00f1\u00edas de Terceros (por ejemplo, proveedores de servicios) o el personal autorizado de nuestros socios de negocio (quien ha aceptado bajo contrato mantener toda la informaci\u00f3n segura) podr\u00e1n tener acceso a su informaci\u00f3n personal siempre que se comprometan a respetar la Pol\u00edtica de Privacidad MERCATOR, del Grupo Transmeridian y la normativa de protecci\u00f3n de datos. Todos los empleados de Terceros quienes tienen acceso a su informaci\u00f3n personal han firmado un acuerdo de confidencialidad en los t\u00e9rminos establecidos en la legislaci\u00f3n vigente. Adem\u00e1s, los contratos est\u00e1n en las compa\u00f1\u00edas de Terceros que tienen acceso a su informaci\u00f3n personal, para asegurar que esta informaci\u00f3n permanezca segura. Para asegurar que su informaci\u00f3n personal est\u00e1 protegida, MERCATOR mantiene un ambiente de IT seguro y ha tomado las medidas necesarias para prevenir accesos sin autorizaci\u00f3n (por ejemplo, hacking), la formulaci\u00f3n de copias y\/o la eliminaci\u00f3n indebida de sus datos personales.<\/p>\n<p><strong>\u00bfPara qu\u00e9 prop\u00f3sito utiliza MERCATOR la informaci\u00f3n personal?<\/strong><\/p>\n<p>Su informaci\u00f3n personal ser\u00e1 utilizada para los prop\u00f3sitos para los cuales usted se la ha proporcionado a MERCATOR, entre ellos, atender tus consultas o reclamos y hacer seguimiento de estos; enviarte informaci\u00f3n o publicidad sobre nuestros productos y servicios; invitarte a participar en nuestros cursos, talleres, concursos, encuestas, entre otras actividades; enviarte muestras o productos relacionados con nuestros productos; realizar la administraci\u00f3n interna de nuestra lista de clientes y estudios de mercado o investigaciones comerciales o estad\u00edsticas; o, simplemente, mantenerte al d\u00eda sobre apasionantes novedades de MERCATOR que te puedan interesar. Tambi\u00e9n ser\u00e1 utilizada para administrar, apoyar y obtener una retroalimentaci\u00f3n acerca del nivel de nuestros servicios y para prevenir infracciones (alteraciones) a nuestra seguridad, la ley y los t\u00e9rminos del contrato.<\/p>\n<p>With your consent for the processing of your personal data, you agree that this shall take precedence over any entry in the register \u201cThank you... don't insist\u201d of Indecopi, the one who replaces him, or any list of lock for the submission of communications. This does not preclude the right of that you have to delete your personal data at any time. Please see Question 5 \u2013 How can you see, check, change, or delete the personal data that you send us?<\/p>\n<p><strong>\u00bfA qui\u00e9n le revela la informaci\u00f3n personal el MERCATOR y y por qu\u00e9?<\/strong><\/p>\n<p>MERCATOR nunca compartir\u00e1 su informaci\u00f3n personal con ninguna organizaci\u00f3n comercial de Terceros que pretendan utilizarla con fines de mercadeo directo, a menos que usted nos haya autorizado de manera espec\u00edfica para ello.<\/p>\n<p>MERCATOR puede compartir su informaci\u00f3n personal con otras compa\u00f1\u00edas dentro del Grupo Transmeridian, el cual est\u00e1 integrado por Transmeridian S.A.C., Antares Aduanas S.A.C., Antares Logisitcs S.A.C., Contrans S.A.C., Transportes Meridian S.A.C, Mercator Per\u00fa &#8211; Operador Log\u00edstico S.A.C., Mercator Bolivia Operador Log\u00edstico S.A. y Universal Per\u00fa &#8211; Operador Log\u00edstico S.A.C.. MERCATOR tambi\u00e9n puede compartir su informaci\u00f3n personal con Terceros, a las que designe, dentro y fuera del territorio nacional, pero solo bajo circunstancias estrictamente limitadas que se detallan a continuaci\u00f3n:<\/p>\n<p>Nosotros podemos proporcionar su informaci\u00f3n personal a Terceros (tales como proveedores de los servicios de hospedaje del sitio web, administradores de p\u00e1ginas web y managers de cuentas en redes sociales) quienes nos ayudan a mantener y administrar este u otros sitios web de MERCATOR (incluyendo, pero no limit\u00e1ndose a las p\u00e1ginas y cuentas que MERCATOR mantiene en redes sociales). Algunos socios de negocio pueden estar ubicados fuera del pa\u00eds donde usted se encuentre al ingresar a este sitio web. Nuestro proveedor principal para el hospedaje del sitio web est\u00e1 en Estados Unidos y es la empresa GoDaddy Operating Company, LLC (encargado del almacenamiento) con domicilio &#8211; EEUU, cuya pol\u00edtica de privacidad puede ser consultada en el siguiente enlace:\u00a0<a href=\"https:\/\/www.godaddy.com\/es\/legal\/agreements\/archived-privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.godaddy.com\/es\/legal\/agreements\/archived-privacy-policy<\/a><\/p>\n<p>Estos Terceros deben, en todo momento, tener los mismos niveles de seguridad tanto de su informaci\u00f3n personal como de MERCATOR y, donde sea requerido, est\u00e1n obligados por un acuerdo legal a mantener su informaci\u00f3n personal privada, segura, confidencial y de procesarla s\u00f3lo bajo instrucciones espec\u00edficas de MERCATOR.<\/p>\n<p>Tambi\u00e9n podemos dar su informaci\u00f3n personal a entidades de la Administraci\u00f3n P\u00fablica y autoridades competentes si: somos requeridos de hacerlo derivado de obligaciones de cualquier ley, o si en nuestra buena fe, tal acci\u00f3n es razonablemente necesaria para cumplir con alg\u00fan proceso legal, para responder a cualquier reclamo o acciones legales; o para proteger los derechos de MERCATOR y\/o del Grupo Transmeridian y\/o sus clientes y del p\u00fablico.<\/p>\n<p>Podemos, en limitadas circunstancias, dar su informaci\u00f3n personal a compradores potenciales de cualquier negocio relevante de MERCATOR, pero teniendo en cuenta que (i) tenemos asegurado bajo contrato que esta informaci\u00f3n sea mantenida privada y segura; y (ii) que cuando al dar esta informaci\u00f3n se d\u00e9 cumplimiento a las leyes locales aplicables.<\/p>\n<p><strong>\u00bfC\u00f3mo y porqu\u00e9 MERCATOR usa la tecnolog\u00eda de rastreo com\u00fanmente conocida como COOKIES?<\/strong><\/p>\n<p>MERCATOR usa la tecnolog\u00eda de rastreo (\u201cCookies\u201d) para recopilar informaci\u00f3n personal pero no datos personales, tales como el tipo de navegador y el sistema operativo, p\u00e1gina de referencia, entre otros, con el objeto de entender la manera en que los visitantes utilizan este sitio Web. Los cookies nos ayudan a adaptar este sitio Web a sus necesidades personales.<\/p>\n<p>MERCATOR mantiene toda la informaci\u00f3n recolectada de los cookies en un formato no-personal, el cual es no identificable. Este tipo de informaci\u00f3n obtenida a trav\u00e9s de cookies no ser\u00e1 divulgada fuera MERCATOR o del Grupo Transmeridian o a Terceros debidamente autorizados. No ser\u00e1 utilizada para comunicaciones no solicitadas.<\/p>\n<p>Los cookies en su computadora no tienen su nombre sino una direcci\u00f3n IP. Despu\u00e9s de cancelar la sesi\u00f3n del usuario, la informaci\u00f3n de los Cookies no est\u00e1 disponible para MERCATOR.<\/p>\n<p>Por favor verifique que la configuraci\u00f3n de su computadora refleje que usted est\u00e1 dispuesto a aceptar cookies o no. Usted puede configurar su navegador para advertirle antes de aceptar cookies o usted puede simplemente configurarla para rechazarlas, aunque usted no pueda tener acceso a todos los atributos de este sitio web si lo hace. En el bot\u00f3n de \u201cayuda\u201d su navegador podr\u00e1 ver c\u00f3mo hacer esto. Usted no necesita tener cookies para usar o navegar a trav\u00e9s de muchas partes de este y de otros sitios web de MERCATOR. Recuerde que si usted utiliza diferentes computadoras en diferentes ubicaciones, usted necesita asegurar que cada navegador est\u00e9 ajustado seg\u00fan sus preferencias de cookies.<\/p>\n<p><strong>\u00bfCu\u00e1nto tiempo mantiene MERCATOR la informaci\u00f3n personal?<\/strong><\/p>\n<p>MERCATOR puede almacenar la informaci\u00f3n personal que nos env\u00eda a trav\u00e9s de este sitio web y cualquier otro del Grupo Transmeridian en sus bases de datos. Su informaci\u00f3n personal ser\u00e1 almacenada por MERCATOR y el Grupo Transmeridian solo por un tiempo justamente razonable para contestar interrogantes o resolver problemas, dar nuevos y mejores servicios y para cumplir con requisitos legales seg\u00fan la(s) ley(es). Esto significa que podemos retener su informaci\u00f3n personal por un periodo de hasta 5 a\u00f1os despu\u00e9s de que usted deje de usar los servicios MERCATOR o este sitio web. Lo anterior en virtud de que las Autoridades pueden verificar el cumplimiento de la legislaci\u00f3n en materia de protecci\u00f3n de datos personales hasta pasados incluso 5 a\u00f1os, despu\u00e9s de este periodo, su informaci\u00f3n personal ser\u00e1 borrada de todos los sistemas de MERCATOR y del Grupo Transmeridian. Le recordamos que tenemos el derecho de borrar su informaci\u00f3n personal en cualquier momento.<\/p>\n<p><strong>\u00bfPuede cambiar MERCATOR los t\u00e9rminos de este Comunicado de Privacidad?<\/strong><\/p>\n<p>Ocasionalmente, MERCATOR podr\u00e1 realizar modificaciones y correcciones en este Comunicado de Privacidad. Por favor, verifica este comunicado regularmente para consultar los cambios que puedan haber existido y de qu\u00e9 manera te pueden afectar.<\/p>\n<h2>14.- ADDITIONAL POLICY DATA PROTECTION<\/h2>\n<p>La Pol\u00edtica de Protecci\u00f3n de Datos Personales de este Sitio ha sido establecida seg\u00fan las disposiciones de la Ley de Protecci\u00f3n de Datos Personales y su Reglamento vigentes en la Rep\u00fablica del Per\u00fa, as\u00ed como por la Pol\u00edtica de Protecci\u00f3n de Datos Personales de MERCATOR. Esta pol\u00edtica tiene como objetivo la protecci\u00f3n y el respeto de los derechos de las personas naturales a tener su vida privada y familiar, correspondencia privada y comunicaciones. Esto incluye el derecho a ser informado y tomar decisiones respecto del procesamiento de sus datos personales.<\/p>\n<p>According to the above, the following definitions apply:<\/p>\n<ul>\n<li>Personal data, or personal Information: Any information relating to a natural person identified or identifiable.<\/li>\n<li>Sensitive data: personal data consisting of biometric data, which themselves can identify the holder, data that relate to the physical characteristics or moral of the people or to the facts or circumstances of his private life or privacy, such as personal habits, racial origins, ideologies and political views, religious beliefs or convictions, states of health, physical or mental, sexual life, trade-union membership, and the information relating to the commission or suspected commission of offences or offences, and the results of the respective judicial proceedings or otherwise.<\/li>\n<li>Data holder: The natural person who is identified or identifiable, to which the personal data refer.<\/li>\n<li>Holder of the bank of personal data: natural person, legal entity of private law or public entity that, either by itself or in conjunction with others, is competent in accordance with peruvian law to determine the purpose, the content and the purpose of the bank of personal data, as well as the means of processing of personal data and the security measures.<\/li>\n<li>Receiver: any natural person or legal entity of private law, including branches, subsidiaries, related or similar authority, or public body, agency or any other entity to whom you disclose or receive personal data, whether or not a third party..<\/li>\n<li>Processing or processing of personal data: any operation or set of operations or technical processing that is performed in respect of personal data, whether or not by automated means, that allow to collect, record, store, retain, modify, record, organize, develop, adapt, alter, select, use, remove, check, confront, interconnect, dissociate, convey, assign, transfer, disclose, disseminate, transmit, align, cancel, block, erase or destroy personal data, or use them in any other form of processing, to facilitate the access, correlation or interconnection of personal data.<\/li>\n<li>Transfer of personal data: any transmission, suministroi or a manifestation of personal data from national or international, a legal person of private law, an entity or a natural person other than the holder of the personal data.<\/li>\n<li>Bank of personal data: organized Set of personal data, whether automated or not, regardless of the medium, either physical, magnetic, digital, optical, or other that you create, whatever the form or manner of its creation, formation, storage, organization or access, which allows us to link the data between themselves, as well as to perform all kinds of data processing.<\/li>\n<\/ul>\n<p>La visita a este Sitio no supone que el Usuario est\u00e9 obligado a proporcionar a MERCATOR sus datos personales. En el caso de que el Usuario proporcione sus datos personales, dichos datos personales recogidos en este Sitio ser\u00e1n utilizados con el prop\u00f3sito, en la forma y con las limitaciones y derechos que recoge la Ley de Protecci\u00f3n de Datos Personales y su Reglamento, de acuerdo a lo previsto en el presente documento, en la Pol\u00edtica de Privacidad y a lo autorizado por el titular del dato personal.<\/p>\n<p>El prop\u00f3sito y el uso de los datos personales que el Usuario proporcione a MERCATOR, est\u00e1n recogidos en el texto legal del respectivo formulario que el Usuario complete en este Sitio. Los datos personales suministrados por los Usuarios no ser\u00e1n procesados de ninguna manera incompatible con los prop\u00f3sitos especificados inicialmente, sin informarles , y obtener nuevamente autorizaci\u00f3n de los Usuarios\/titulares de los datos personales respectivos.<\/p>\n<p>Los datos personales solicitados por MERCATOR a sus Usuarios ser\u00e1n adecuados, relevantes y no ser\u00e1n excesivos en relaci\u00f3n con el prop\u00f3sito espec\u00edfico para el cual fueron solicitados. MERCATOR proceder\u00e1 a la cancelaci\u00f3n o eliminaci\u00f3n de los datos personales recogidos cuando \u00e9stos dejen de ser necesarios o pertinentes para el prop\u00f3sito para el que hubiesen sido recabados o registrados.<\/p>\n<p>Al momento de recabar datos personales, el titular de los mismos debe dar a MERCATOR, o a la persona natural o jur\u00eddica designada por MERCATOR, su consentimiento inequ\u00edvoco antes de que sus datos personales sean procesados. Este consentimiento puede ser obtenido por medios electr\u00f3nicos, siempre que el mismo sea gratuito e inequ\u00edvoco. Hacer clic en los botones \u201cproceder\u201d, \u201caceptar\u201d o \u201ccontinuar\u201d en la pantalla ser\u00e1 suficiente para entender que el consentimiento ha sido otorgado de manera previa, expresa, informada e inequ\u00edvoca, siempre que tambi\u00e9n est\u00e9 el bot\u00f3n \u201ccancelar\u201d.<\/p>\n<p>Los Usuarios que faciliten sus datos personales, consienten inequ\u00edvocamente la incorporaci\u00f3n de los mismos en un banco de datos personales del que ser\u00e1 titular, responsable y\/o encargado MERCATOR, o una persona natural o jur\u00eddica designada por MERCATOR, as\u00ed como del procesamiento o no de los datos personales. Esta informaci\u00f3n ser\u00e1 tratada con sumo cuidado, con confidencialidad y con la mayor seguridad posible y s\u00f3lo se utilizar\u00e1 de acuerdo a los l\u00edmites establecidos en este documento y en los t\u00e9rminos previstos en la autorizaci\u00f3n o consentimiento que emita el titular del dato personal.<\/p>\n<p>Los datos personales deber\u00e1n ser veraces. MERCATOR s\u00f3lo re\u00fane datos personales cuando estos son proporcionados directamente por los Usuarios del Sitio.<\/p>\n<p>In the case that the data collected would be used for a purpose or purposes other than those originally authorized or planned, will be required and will be managed by the consent of those concerned.<\/p>\n<p>Al entregar sus datos personales, el Usuario autoriza a MERCATOR a utilizarlos de acuerdo a las pol\u00edticas establecidas en este documento, con la seguridad y privacidad requeridas. Cada vez que el Usuario ingresa sus datos personales, deber\u00e1 aceptar o rechazar el uso en futuras comunicaciones. Al completar cualquier formulario si no est\u00e1 de acuerdo con esto, el Usuario deber\u00e1 desactivar la opci\u00f3n respectiva. Si elige mantenerla activada, se entiende que el Usuario autoriza a MERCATOR al uso de los datos personales para los fines y con los prop\u00f3sitos expuestos.<\/p>\n<p>Los datos sensibles no ser\u00e1n procesados por MERCATOR excepto si el titular de los mismos da su consentimiento previo, expreso, informado, inequ\u00edvoco y por escrito para ello, y cuando (i) sean requeridos conforme a la ley aplicable, (ii) cuando dicho procesamiento de datos sensibles sea necesario para proteger intereses vitales del titular de los mismos o de otra persona; (iii) cuando el procesamiento se refiera a datos personales sean revelados p\u00fablicamente por su titular; o (iv) cuando el procesamiento sea necesario para el establecimiento, ejercicio o defensa de demandas legales.<\/p>\n<p>MERCATOR ha adoptado las medidas t\u00e9cnicas. F\u00edsicas, tecnol\u00f3gicas, legales y organizativas necesarias para garantizar la seguridad, confidencialidad e integridad de los datos personales, as\u00ed como para evitar su alteraci\u00f3n, p\u00e9rdida accidental, destrucci\u00f3n, tratamiento o acceso no autorizado. Las medidas adoptadas por MERCATOR ser\u00e1n proporcionales a los riesgos involucrados en el procesamiento de los datos personales. No obstante, en la actualidad ning\u00fan sistema es completamente seguro o libre de ataques.<\/p>\n<p>Users whose personal data are subject to processing may freely exercise the following rights:<\/p>\n<ol>\n<li><strong>Right of access:<\/strong>\u00a0The holder has the right to obtain information upon himself to be the object of treatment in banks of management data, public or private, the way in which your data were collected, the reasons that led to your collection and at the request of those who carried out the collection, as well as transfers made or are planning to do with them.<br \/><br \/><\/li>\n<li><strong>Right to update, inclusion, correction and deletion:<\/strong>\u00a0The holder of personal data has the right to update, inclusion, rectification and deletion of your personal data subject to processing, where these are partially or totally inaccurate, incomplete, when it has warned any omission, error or falsehood, when they are no longer necessary or relevant to the purpose for which they were collected or, when there is the expiry of the deadline established for its treatment.<br \/><br \/>If their personal data had been transferred previously, the manager of the bank of personal data must communicate the update, inclusion, rectification or deletion of those who have been transferred, in the case that you keep the treatment by the latter, who must also proceed with the update, inclusion, rectification or deletion, as applicable.<br \/><br \/>During the upgrade process, inclusion, rectification or erasure of personal data, the manager of the bank of personal data has its lock, being prevented from allowing third parties to have access to them. This lock is not applicable to public entities that require such information for the proper exercise of its powers, according to law, the Peruvian Legal Information Ministry of Justice 10\/10\/2011 10:46 AM Page 8 Updated: 28\/09\/11 who should report that is in the process of any of the above mentioned processes.<br \/><br \/><\/li>\n<li><strong>The right to prevent the supply:<\/strong>\u00a0The holder of personal data has the right to prevent these will be provided, especially when it affects your fundamental rights. The right to prevent the provision does not apply to the relationship between the holder of the bank of personal data and the manager of the bank of the personal data for the purposes of the treatment of these.<br \/><br \/><\/li>\n<li><strong>Right of opposition:<\/strong>\u00a0Provided that, by law, not otherwise provided for and when he would not have given consent, the holder of personal data may oppose the treatment when there are well-founded reasons and legitimate relating to a specific personal situation. In case of a justified objection, the owner or the manager of the bank of personal data, as appropriate, must proceed to its suppression, in accordance with law.<\/li>\n<\/ol>\n<p>Todos estos derechos, m\u00e1s los que concede la Ley N\u00b029733 de Protecci\u00f3n de Datos Personales y su Reglamento, podr\u00e1n ser ejercitados dirigiendo comunicaci\u00f3n v\u00eda e-mail a MERCATOR a la casilla de correo electr\u00f3nico\u00a0<a href=\"mailto:csaavedra@antareslogistics.com.pe\">csaavedra@antareslogistics.com.pe<\/a>, o mediante carta enviada a MERCATOR, sitio en <b>Av. Rep\u00fablica de Colombia 717. Piso 8. San Isidro &#8211; Lima<\/b><\/p>\n<p>At the time of the collection of personal data, will indicate the voluntary or compulsory nature of the personal data being collected.<\/p>\n<p>Access to this Website may involve the use of cookies. Cookies are small amounts of information which are stored in the browser used by each User for the server to remember certain information that later and only the server that implemented it will read. Cookies have, in general, a limited time duration. No cookies on this Site to allow contact with the User's telephone number, your e-mail address or with any other means of contact. No cookie from this Site can extract information from the User's hard drive or steal personal information. The only way, in this Site, of which the private information of a User forms part of the cookie file is if the User personally gives that information to the server. Those Users who do not wish to receive cookies or want to be informed of their presence may configure their browser to that effect.<\/p>\n<h2>15.- MISCELLANEOUS<\/h2>\n<ul>\n<li>Cualquier material o dato personal enviado a las p\u00e1ginas web de MERCATOR o del Grupo Transmeridian queda amparado por la pol\u00edtica de privacidad de dicho Grupo y por la protecci\u00f3n de datos personales expuesta en los Puntos 13, 14 y 15 de los T\u00e9rminos y Condiciones que se encuentra en esta misma p\u00e1gina web.<\/li>\n<li>Although we use all means at our disposal to ensure the accuracy and completeness of the information contained on this website. We do not assume any responsibility in the event that the information which is available on the same not be accurate or complete. Any modification you do on the material available on this website will be at your own risk. In addition, you agree that it is your responsibility to verify any changes which may occur.<\/li>\n<li>Cualquier material o comunicaci\u00f3n no personal que transmitas a esta p\u00e1gina web por e-mail o cualquier otro medio, incluyendo datos, preguntas, comentarios, sugerencias o similares, es y ser\u00e1 tratada como no confidencial y sin derechos de propiedad. Cualquier cosa que transmitas o que coloques en la p\u00e1gina pasa a ser propiedad de MERCATOR y\/o del Grupo Transmeridian y se puede utilizar para cualquier finalidad, incluyendo, sin car\u00e1cter limitativo, la reproducci\u00f3n, acceso, transmisi\u00f3n, publicaci\u00f3n, emisi\u00f3n y colocaci\u00f3n de contenidos en la web. A\u00fan m\u00e1s, MERCATOR y el Grupo Transmeridian son totalmente libres de usar, para cualquier finalidad que estime oportuna (incluyendo, sin car\u00e1cter limitativo, el desarrollo, fabricaci\u00f3n, publicidad y marketing de productos), las ideas, material gr\u00e1fico, invenciones, desarrollos, sugerencias o conceptos en general contenidos en cualquier comunicaci\u00f3n que env\u00edes a esta p\u00e1gina web. Dicho uso no tendr\u00e1 compensaci\u00f3n para la parte que ha facilitado la informaci\u00f3n. Facilitando informaci\u00f3n, tambi\u00e9n est\u00e1s garantizando que eres el propietario del material\/contenido proporcionado, que no es de car\u00e1cter difamatorio y que su uso por parte de MERCATOR y\/o del Grupo Transmeridian no violar\u00e1 derechos de terceras personas ni comportar\u00e1 un incumplimiento por nuestra parte de la legislaci\u00f3n aplicable. MERCATOR y el Grupo Transmeridian no tienen ninguna obligaci\u00f3n de utilizar la informaci\u00f3n facilitada.<\/li>\n<li>Todos los derechos de autor y dem\u00e1s derechos de propiedad intelectual referentes a los textos, im\u00e1genes y materiales en general contenidos en esta p\u00e1gina web son propiedad de MERCATOR y del Grupo Transmeridian o han sido incluidos con la autorizaci\u00f3n de su correspondiente propietario.<\/li>\n<li>The use of this website is exclusively at your own risk.<\/li>\n<li>Esta p\u00e1gina web se ofrece \u00abcuando es posible\u00bb y \u00abtal cual est\u00e1\u00bb y, por tanto, MERCATOR y\/o el Grupo Transmeridian no dan garant\u00edas de ning\u00fan tipo, ya sean expl\u00edcitas, impl\u00edcitas, legales o de otro tipo (incluso las garant\u00edas impl\u00edcitas de comerciabilidad o satisfacci\u00f3n del nivel de calidad y de adecuaci\u00f3n a un prop\u00f3sito particular), incluyendo garant\u00edas o compromisos en relaci\u00f3n a que el material de esta p\u00e1gina web ser\u00e1 completo, exacto, fiable, puesto al d\u00eda, respetuoso con los derechos de terceros, que el acceso a esta p\u00e1gina web no sufrir\u00e1 interrupciones, no presentar\u00e1 errores y estar\u00e1 exento de virus, que esta p\u00e1gina web ser\u00e1 segura y que cualquier opini\u00f3n o consejo del Grupo Transmeridian obtenido a trav\u00e9s de esta p\u00e1gina web ser\u00e1 exacto o fiable, por todo lo cual se indica expresamente que no se asumir\u00e1 ning\u00fan compromiso o garant\u00eda sobre los aspectos enumerados.<\/li>\n<li>We reserve the right to restrict, suspend, or cancel, without prior notice and at any time, your access to this website, or to a part of the same and any functionality that is built into the page.<\/li>\n<li>Tanto MERCATOR como el Grupo Transmeridian o como cualquier tercero implicado en la creaci\u00f3n, producci\u00f3n o distribuci\u00f3n de esta p\u00e1gina web en nuestro nombre no tendr\u00e1n ning\u00fan tipo de responsabilidad, en ning\u00fan caso, por da\u00f1os directos, fortuitos, consecutivos, indirectos, especiales o punitivos ni por costes, p\u00e9rdidas o responsabilidades, cualquiera que sea la forma en que se deriven de tu acceso, uso o incapacidad de uso, del cambio en el contenido de esta p\u00e1gina web, de cualquier otra p\u00e1gina web a la que accediste por medio de un enlace proporcionado en esta p\u00e1gina o de la m\u00e1xima amplitud permitida por la legislaci\u00f3n aplicable, motivados por cualquier medida que nosotros tomamos o dejamos de tomar como resultado de alg\u00fan mensaje que nos enviaste por e-mail.<\/li>\n<li>Tanto MERCATOR como el Grupo Transmeridian como cualquier tercero implicado en la creaci\u00f3n, producci\u00f3n o distribuci\u00f3n de esta p\u00e1gina web no tendr\u00e1n ninguna responsabilidad derivada de mantener el material y los servicios que se encuentran disponibles en esta p\u00e1gina o de realizar correcciones, actualizaciones o eliminaciones de los mismos. Cualquier material contenido en esta p\u00e1gina web est\u00e1 sujeto a cambios sin previo aviso.<\/li>\n<li>A\u00fan m\u00e1s, MERCATOR y el Grupo Transmeridian no tendr\u00e1n ning\u00fan tipo de responsabilidad, en ning\u00fan caso, por cualquier da\u00f1o sufrido a consecuencia de alg\u00fan virus que pueda haber infectado tu ordenador u otros aparatos de tu propiedad por causa de tu acceso, uso o descargas de cualquier material de esta p\u00e1gina web. Si optas por descargar material desde esta p\u00e1gina web, esa acci\u00f3n se realiza por tu exclusiva cuenta y riesgo.<\/li>\n<li>Con la m\u00e1xima amplitud permitida por la legislaci\u00f3n aplicable, declaras renunciar expresamente a efectuar cualquier reclamaci\u00f3n contra MERCATOR y\/o el Grupo Transmeridian y sus responsables, directores, empleados, proveedores y programadores que se pueda derivar de tu uso o acceso a esta p\u00e1gina web.<\/li>\n<li>Tienes prohibido realizar cualquier acto que, a juicio de MERCATOR o del Grupo Transmeridian, se pueda considerar inapropiado y\/o llegar a considerarse como un acto ilegal o que est\u00e9 prohibido de acuerdo con la legislaci\u00f3n aplicable a esta p\u00e1gina web, incluyendo, sin car\u00e1cter limitativo, los siguientes: Cualquier acto que constituir\u00eda un incumplimiento de la privacidad (incluyendo transferencias a la p\u00e1gina web de informaci\u00f3n privada sin la autorizaci\u00f3n de la persona afectada) o de cualquier otro de los derechos legales de las personas f\u00edsicas; usar esta p\u00e1gina web para difamar o calumniar a MERCATOR o al Grupo Transmeridian, sus empleados u otras personas f\u00edsicas, o actuar de tal manera que se desacredite el buen nombre de MERCATOR o del Grupo Transmeridian, transferir a la p\u00e1gina web archivos que contengan virus que puedan causar da\u00f1os a la propiedad de MERCATOR o del Grupo Transmeridian o a la propiedad de personas f\u00edsicas y colocar o transmitir a esta p\u00e1gina web cualquier material no autorizado, incluyendo, sin car\u00e1cter limitativo, material que probablemente cause, a juicio nuestro, molestias o perjuicios, o bien, violando los sistemas o la seguridad de la red de MERCATOR o del Grupo Transmeridian o de terceras personas, material que sea difamatorio, racista, obsceno, amenazador, de contenido pornogr\u00e1fico o que presente cualquier forma de ilegalidad en general.<\/li>\n<\/ul>\n<p>El material y la informaci\u00f3n de MERCATOR o del Grupo Transmeridian que aparecen en esta p\u00e1gina web han sido incluidos \u00fanicamente para los usuarios de Per\u00fa. MERCATOR y el Grupo Transmeridian no asumen ning\u00fan compromiso en relaci\u00f3n a que el material y la informaci\u00f3n de esta p\u00e1gina web sean apropiados o se encuentren disponibles en zonas distintas a Per\u00fa.<\/p>\n<p>El usuario de esta p\u00e1gina web y MERCATOR y el Grupo Transmeridian aceptan que cualquier controversia o reclamaci\u00f3n derivada o referente al uso de esta p\u00e1gina web se resolver\u00e1 seg\u00fan las leyes de Per\u00fa, y se someter\u00e1 exclusivamente a la jurisdicci\u00f3n de los Juzgados y Tribunales de Per\u00fa.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Gracias por visitar este sitio web. Por favor lea con cuidado los\u00a0T\u00c9RMINOS Y CONDICIONES DE USO\u00a0contenidos en este documento ya que cualquier uso de este sitio web constituye su aceptaci\u00f3n t\u00e1cita y\/o expresa a los mismos. En otras palabras, cada vez que se usa esta p\u00e1gina web se est\u00e1n aceptando \u00edntegramente los T\u00e9rminos y Condiciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1428","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/mail.mercator.com.pe\/en\/wp-json\/wp\/v2\/pages\/1428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.mercator.com.pe\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mail.mercator.com.pe\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mail.mercator.com.pe\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mail.mercator.com.pe\/en\/wp-json\/wp\/v2\/comments?post=1428"}],"version-history":[{"count":12,"href":"https:\/\/mail.mercator.com.pe\/en\/wp-json\/wp\/v2\/pages\/1428\/revisions"}],"predecessor-version":[{"id":3048,"href":"https:\/\/mail.mercator.com.pe\/en\/wp-json\/wp\/v2\/pages\/1428\/revisions\/3048"}],"wp:attachment":[{"href":"https:\/\/mail.mercator.com.pe\/en\/wp-json\/wp\/v2\/media?parent=1428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}